{"id":74,"date":"2024-11-22T14:33:07","date_gmt":"2024-11-22T13:33:07","guid":{"rendered":"https:\/\/vimasteprata.nu\/?page_id=74"},"modified":"2026-01-10T14:28:58","modified_gmt":"2026-01-10T13:28:58","slug":"vimasteprata-nu","status":"publish","type":"page","link":"https:\/\/vimasteprata.nu\/ar\/","title":{"rendered":"\u064a\u062c\u0628 \u0623\u0646 \u0646\u062a\u062d\u062f\u062b \u0627\u0644\u0622\u0646"},"content":{"rendered":"<div class=\"gb-element-079bb311 alignfull\">\n<div>\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#AKUT\" style=\"background:linear-gradient(180deg,rgb(197,9,9) 0%,rgb(0,0,0) 100%);padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0628\u064e\u0635\u0650\u064a\u0631<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#BARN-UNGDOM\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0627\u0644\u0623\u0637\u0641\u0627\u0644 \u0648\u0627\u0644\u0634\u0628\u0627\u0628<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#KVINNA\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0627\u0645\u0631\u0623\u0629<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#MAN\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0631\u062c\u0644<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#HBTQIA\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>LGBTQIA +<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#SENIOR\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0643\u0628\u064a\u0631<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#F\u00d6R\u00c4LDER\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0627\u0644\u0648\u0627\u0644\u062f<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#F\u00d6R-ALLA\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0644\u0644\u062c\u0645\u064a\u0639<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#Alkohol\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0627\u0644\u0643\u062d\u0648\u0644 \u0648\u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-c71ee733 wp-block-columns-is-layout-flex\" style=\"padding-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fdd94e84 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"#Spel\" style=\"background:linear-gradient(180deg,rgb(0,76,16) 0%,rgb(0,0,0) 100%);box-shadow:var(--wp--preset--shadow--natural)\"><strong>\u0644\u0639\u0628\u0629<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"AKUT\" style=\"margin-top:var(--wp--preset--spacing--50)\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akut2-1024x171.png\" alt=\"Banner med texten AKUT Vi m\u00e5ste prata nu\" class=\"wp-image-195\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akut2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akut2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akut2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akut2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SOS-Alarm-1.png\" alt=\"Bild med texten SOS Alarm\" class=\"wp-image-90\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SOS-Alarm-1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SOS-Alarm-1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0625\u0646\u0630\u0627\u0631 SOS<\/strong><br>\u0631\u0642\u0645 \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0641\u064a \u0627\u0644\u0633\u0648\u064a\u062f \u0644\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0641\u064a \u062d\u0627\u0644\u0627\u062a \u0627\u0644\u0637\u0648\u0627\u0631\u0626.<br><br>\u064a\u062c\u0628 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0631\u0642\u0645 \u0627\u0644\u0637\u0648\u0627\u0631\u0626 112 \u0641\u064a \u062d\u0627\u0644\u0627\u062a \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0627\u0644\u0639\u0627\u062c\u0644\u0629 \u0639\u0646\u062f\u0645\u0627 \u064a\u0643\u0648\u0646 \u0647\u0646\u0627\u0643 \u062e\u0637\u0631 \u0639\u0644\u0649 \u0627\u0644\u062d\u064a\u0627\u0629 \u0623\u0648 \u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a \u0623\u0648 \u0627\u0644\u0628\u064a\u0626\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: 112\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.sosalarm.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mind-Sjalvmordslinjen.png\" alt=\"Bild med texten Mind Sj\u00e4lvmordslinjen\" class=\"wp-image-91\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mind-Sjalvmordslinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mind-Sjalvmordslinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0645\u0627\u064a\u0646\u062f: \u062e\u0637 \u0627\u0644\u0627\u0646\u062a\u062d\u0627\u0631<\/strong><br>\u062f\u0639\u0645 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u0644\u062f\u064a\u0647\u0645 \u0623\u0641\u0643\u0627\u0631 \u0627\u0646\u062a\u062d\u0627\u0631\u064a\u0629 \u0623\u0648 \u0627\u0644\u0630\u064a\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0623\u0632\u0645\u0629.<br><br>\u0627\u062a\u0635\u0644 \u0623\u0648 \u062f\u0631\u062f\u0634 \u0645\u0639 MIND \u0645\u0628\u0627\u0634\u0631\u0629.<br>\u0647\u0646\u0627\u0643 \u0646\u0635\u0627\u0626\u062d \u0648\u062f\u0639\u0645 \u0644\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0639\u0642\u0644\u064a\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"tel:90101\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:55px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a class=\"ub_icon_wrapper\" href=\"https:\/\/mind.se\/stod-kunskap\/prata-eller-chatta-med-volontar\/sjalvmordslinjen\/chatt\/\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 32C114.6 32 0 125.1 0 240c0 49.6 21.4 95 57 130.7C44.5 421.1 2.7 466 2.2 466.5c-2.2 2.3-2.8 5.7-1.5 8.7S4.8 480 8 480c66.3 0 116-31.8 140.6-51.4 32.7 12.3 69 19.4 107.4 19.4 141.4 0 256-93.1 256-208S397.4 32 256 32zM128 272c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm128 0c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32zm128 0c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32z\"><\/path><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/mind.se\/stod-kunskap\/prata-eller-chatta-med-volontar\/sjalvmordslinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Hjalplinjen4.png\" alt=\"Logotyp f\u00f6r Hj\u00e4lplinjen\" class=\"wp-image-490\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Hjalplinjen4.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Hjalplinjen4-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629<\/strong><br>\u062e\u0637 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u062e\u062f\u0645\u0629 \u062f\u0639\u0645 \u0645\u062c\u0627\u0646\u064a\u0629 \u0648\u0645\u062c\u0647\u0648\u0644\u0629 \u0627\u0644\u0645\u0635\u062f\u0631 \u0644\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u062a\u0632\u064a\u062f \u0623\u0639\u0645\u0627\u0631\u0647\u0645 \u0639\u0646 18 \u0639\u0627\u0645\u064b\u0627 \u0648\u0627\u0644\u0630\u064a\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0623\u0632\u0645\u0629 \u0623\u0648 \u0648\u0636\u0639 \u062d\u064a\u0627\u062a\u064a \u0635\u0639\u0628 \u0623\u0648 \u0644\u062f\u064a\u0647\u0645 \u0623\u0641\u0643\u0627\u0631 \u0627\u0646\u062a\u062d\u0627\u0631\u064a\u0629 \u0623\u0648 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0645\u0634\u0627\u0643\u0644 \u0646\u0641\u0633\u064a\u0629.<br><br>\u0646\u062d\u0646 \u0646\u0642\u062f\u0645 \u062f\u0639\u0645\u064b\u0627 \u0627\u062d\u062a\u0631\u0627\u0641\u064a\u064b\u0627 \u0639\u0644\u0649 \u0645\u062f\u0627\u0631 \u0627\u0644\u0633\u0627\u0639\u0629\u060c \u0637\u0648\u0627\u0644 \u0627\u0644\u0639\u0627\u0645\u060c \u0644\u0643\u0644 \u0645\u0646 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u064a\u0628\u062d\u062b\u0648\u0646 \u0639\u0646 \u0627\u0644\u062f\u0639\u0645 \u0644\u0631\u0641\u0627\u0647\u064a\u062a\u0647\u0645 \u0648\u0644\u0623\u0642\u0627\u0631\u0628\u0647\u0645.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"tel:90390\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/hjalplinjen.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"border-style:none;border-width:0px;border-radius:5px;padding-top:var(--wp--preset--spacing--20);padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0\">\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"BARN-UNGDOM\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BarnUngdom2-1024x171.png\" alt=\"Banner med texten Barn och ungdom\" class=\"wp-image-196\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BarnUngdom2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BarnUngdom2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BarnUngdom2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BarnUngdom2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/bris.png\" alt=\"Bild med texten BRIS\" class=\"wp-image-112\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/bris.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/bris-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0646\u0633\u064a\u0645 \u2013<\/strong> \u062d\u0642\u0648\u0642 \u0627\u0644\u0637\u0641\u0644 \u0641\u064a \u0627\u0644\u0645\u062c\u062a\u0645\u0639<br>\u0647\u0646\u0627\u060c \u064a\u0645\u0643\u0646\u0643 \u0644\u0645\u0646 \u0647\u0645 \u0623\u0642\u0644 \u0645\u0646 18 \u0639\u0627\u0645\u064b\u0627 \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u062f\u0639\u0645 \u0645\u062c\u0627\u0646\u064a \u0648\u0645\u062c\u0647\u0648\u0644 \u0645\u0646 \u0623\u062d\u062f \u0627\u0644\u0645\u0633\u062a\u0634\u0627\u0631\u064a\u0646 \u0641\u064a Bris.<br><br><br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0647\u0627\u062a\u0641: 116111\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/barn.bris.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tjejzonen1.png\" alt=\"Logotyp Tjejzonen\" class=\"wp-image-334\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tjejzonen1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tjejzonen1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0645\u0646\u0637\u0642\u0629 \u0627\u0644\u0641\u062a\u0627\u0629<\/strong><br>\u0623\u0643\u0628\u0631 \u0645\u0646\u0638\u0645\u0629 \u062f\u0639\u0645 \u0644\u0644\u0641\u062a\u064a\u0627\u062a \u0641\u064a \u0627\u0644\u0633\u0648\u064a\u062f. <br>\u0646\u062d\u0646 \u0646\u0646\u0627\u0636\u0644 \u0645\u0646 \u0623\u062c\u0644 \u062d\u0642 \u062c\u0645\u064a\u0639 \u0627\u0644\u0641\u062a\u064a\u0627\u062a \u0641\u064a \u0623\u0646 \u064a\u062a\u0645 \u0627\u0644\u0627\u0633\u062a\u0645\u0627\u0639 \u0644\u0647\u0646 \u0648\u0645\u0646 \u0623\u062c\u0644 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u0635\u062d\u0629 \u0627\u0644\u0639\u0642\u0644\u064a\u0629 \u0628\u064a\u0646 \u0643\u0644 \u0645\u0646 \u064a\u0639\u0631\u0641 \u0646\u0641\u0633\u0647 \u0643\u0641\u062a\u0627\u0629 \u0648\u064a\u062a\u0631\u0627\u0648\u062d \u0639\u0645\u0631\u0647 \u0628\u064a\u0646 10 \u064825 \u0639\u0627\u0645\u064b\u0627.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:info@tjejzonen.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/tjejzonen.se\/stodchattarna\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Friends.png\" alt=\"Bild med texten Friends\" class=\"wp-image-303\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Friends.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Friends-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0623\u0635\u062f\u0642\u0627\u0621<\/strong> <br>\u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0645\u0648\u062c\u0648\u062f\u0648\u0646 \u0644\u0623\u0648\u0644\u0626\u0643 \u0627\u0644\u0630\u064a\u0646 \u064a\u062d\u062a\u0627\u062c\u0648\u0646 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0648\u0631\u0629 \u0648\u0627\u0644\u062f\u0639\u0645 \u0641\u064a\u0645\u0627 \u064a\u062a\u0639\u0644\u0642 \u0628\u0627\u0644\u0642\u0636\u0627\u064a\u0627 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0636\u0639\u0641 \u0648\u0627\u0644\u062a\u0646\u0645\u0631 \u0648\u0627\u0644\u0648\u062d\u062f\u0629 \u0648\u0627\u0644\u0645\u0632\u064a\u062f.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-54551990\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/friends.se\/kunskapsbanken\/barn-och-unga\/rad-och-stod\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/UMO3.png\" alt=\"Logotyp UMO\" class=\"wp-image-332\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/UMO3.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/UMO3-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>UMO<\/strong><br>UMO \u0647\u0648 \u0645\u0648\u0642\u0639 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0645\u062e\u0635\u0635 \u0644\u0643\u0644 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u062a\u062a\u0631\u0627\u0648\u062d \u0623\u0639\u0645\u0627\u0631\u0647\u0645 \u0628\u064a\u0646 13 \u064825 \u0639\u0627\u0645\u064b\u0627. \u0641\u064a UMO.se \u064a\u0645\u0643\u0646\u0643 \u0627\u0643\u062a\u0633\u0627\u0628 \u0627\u0644\u0645\u0639\u0631\u0641\u0629 \u062d\u0648\u0644 \u0627\u0644\u062c\u0633\u0645 \u0648\u0627\u0644\u062c\u0646\u0633 \u0648\u0627\u0644\u0639\u0644\u0627\u0642\u0627\u062a \u0648\u0627\u0644\u0635\u062d\u0629 \u0627\u0644\u0639\u0642\u0644\u064a\u0629 \u0648\u0627\u0644\u0643\u062d\u0648\u0644 \u0648\u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a \u0648\u0627\u062d\u062a\u0631\u0627\u0645 \u0627\u0644\u0630\u0627\u062a \u0648\u063a\u064a\u0631 \u0630\u0644\u0643 \u0627\u0644\u0643\u062b\u064a\u0631.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.umo.se\/att-ta-hjalp\/hit-kan-du-ringa-maila-eller-chatta\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Ecpat.png\" alt=\"Bild med texten ECPAT\" class=\"wp-image-309\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Ecpat.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Ecpat-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0625\u064a\u0643\u0628\u0627\u062a<\/strong><br>\u0627\u062a\u0635\u0644 \u0628\u0646\u0627 \u0623\u0648 \u062a\u062d\u062f\u062b \u0645\u0639\u0646\u0627 \u0625\u0630\u0627 \u0643\u0627\u0646\u062a \u0644\u062f\u064a\u0643 \u0623\u0633\u0626\u0644\u0629 \u0623\u0648 \u0625\u0630\u0627 \u062d\u062f\u062b \u0644\u0643 \u0634\u064a\u0621 \u0635\u0639\u0628. <br>\u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0643\u0648\u0646\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u062d\u0648\u0644:<br>\u0627\u0644\u0645\u0648\u0627\u0641\u0642\u0629\u060c \u0623\u0648 \u0627\u0644\u0627\u0639\u062a\u062f\u0627\u0621 \u0627\u0644\u062c\u0646\u0633\u064a\u060c \u0623\u0648 \u0627\u0644\u0639\u0631\u064a\u060c \u0623\u0648 \u0623\u064a \u0634\u064a\u0621 \u062c\u0646\u0633\u064a \u062d\u062f\u062b \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0648\u0644\u0645 \u064a\u0643\u0646 \u064a\u0628\u062f\u0648 \u0639\u0644\u0649 \u0645\u0627 \u064a\u0631\u0627\u0645.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-112100\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/dittecpat.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Natvandrarchatten.png\" alt=\"\" class=\"wp-image-405\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Natvandrarchatten.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Natvandrarchatten-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062f\u0631\u062f\u0634\u0629 \u0627\u0644\u0645\u062a\u062c\u0648\u0644<\/strong><br>\u0645\u0643\u0627\u0646 \u062f\u0627\u0639\u0645 \u0644\u0643 \u0627\u0644\u0630\u064a\u0646 \u062a\u062a\u0631\u0627\u0648\u062d \u0623\u0639\u0645\u0627\u0631\u0647\u0645 \u0628\u064a\u0646 12 \u064825 \u0639\u0627\u0645\u064b\u0627 \u062d\u064a\u062b \u064a\u0633\u062a\u0645\u0639 \u0627\u0644\u0643\u0628\u0627\u0631 \u0627\u0644\u0622\u0645\u0646\u0648\u0646 \u0648\u0627\u0644\u062d\u0627\u0636\u0631\u0648\u0646. <br>\u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0628\u0634\u0643\u0644 \u0645\u062c\u0647\u0648\u0644 \u062a\u0645\u0627\u0645\u0627 \u0639\u0646 \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0648\u0627\u0644\u0645\u0634\u0627\u0639\u0631 \u0648\u0627\u0644\u062d\u064a\u0627\u0629.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/kyrkanssos.se\/hitta-hjalp\/natvandrarchatten\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/GAPF1.png\" alt=\"Logotyp f\u00f6r GAPF\" class=\"wp-image-495\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 GAPF - \u0644\u0627 \u062a\u0646\u0633\u0648\u0627 \u0623\u0628\u062f\u064b\u0627 \u0628\u064a\u0644\u0627 \u0648\u0641\u0627\u062f\u064a\u0645\u064a<\/strong><em> <\/em>\u062a\u0639\u0645\u0644 \u0645\u0646 \u0623\u062c\u0644 \u0645\u062c\u062a\u0645\u0639 \u0645\u062a\u0633\u0627\u0648\u064d \u0648\u062e\u0627\u0644\u064a \u0645\u0646 \u0627\u0644\u0639\u0646\u0641 \u0648\u0627\u0644\u0642\u0645\u0639 \u0627\u0644\u0645\u0631\u062a\u0628\u0637 \u0628\u0627\u0644\u0634\u0631\u0641.<br><br>\u0647\u0644 \u062a\u062a\u0639\u0631\u0636\u064a\u0646 \u0623\u0648 \u062a\u062a\u0623\u062b\u0631\u064a\u0646 \u0628\u0627\u0644\u0639\u0646\u0641 \u0648\u0627\u0644\u0642\u0645\u0639 \u0627\u0644\u0645\u0631\u062a\u0628\u0637 \u0628\u0627\u0644\u0634\u0631\u0641\u061f \u0647\u0646\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0648\u0627\u0644\u0645\u0634\u0648\u0631\u0629\u060c \u0641\u0636\u0644\u0627 \u0639\u0646 \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u064a. <br>\u0627\u062a\u0635\u0644 \u0628\u0627\u0644\u062e\u0637 \u0627\u0644\u0633\u0627\u062e\u0646 \u0644\u0644\u062f\u0639\u0645 \u0639\u0644\u0649 <a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4670-0009328\/\">070 000 9328<\/a> \u0623\u0648 \u0627\u062a\u0635\u0644 \u0628\u0646\u0627 \u0639\u0644\u0649 <a href=\"http:\/\/gapf.se\" target=\"_blank\" rel=\"noreferrer noopener\">\u0641\u062c\u0648\u0629.se<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4670-0009328\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:stodjour@gapf.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/gapf.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Storasyster1.png\" alt=\"Logotyp f\u00f6r Storasyster\" class=\"wp-image-491\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Storasyster1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Storasyster1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u0623\u062e\u062a \u0627\u0644\u0643\u0628\u0631\u0649.org<\/strong><br>\u0645\u0639\u0646\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0644\u062f\u0639\u0645 \u0648\u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0625\u0630\u0627 \u062a\u0639\u0631\u0636\u062a \u0644\u0627\u0639\u062a\u062f\u0627\u0621 \u062c\u0646\u0633\u064a \u0648\u0623\u0646\u062a \u0643\u0623\u062d\u062f \u0623\u0642\u0627\u0631\u0628\u0643\u060c \u0641\u0646\u062d\u0646 \u0646\u0642\u0628\u0644\u0643 \u0645\u0646 \u0633\u0646 13 \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0647\u0648\u064a\u062a\u0643 \u0627\u0644\u062c\u0646\u0633\u064a\u0629. <br>\u064a\u0645\u0643\u0646\u0643 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0645\u062c\u0647\u0648\u0644 \u0627\u0644\u0647\u0648\u064a\u0629 \u062a\u0645\u0627\u0645\u064b\u0627 \u0648\u0644\u062f\u064a\u0646\u0627 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0648\u0638\u0627\u0626\u0641 \u0627\u0644\u062f\u0639\u0645.<br><br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/storasyster.org\/stod-och-hjalp-efter-sexuella-overgrepp\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Ungarelationer1.png\" alt=\"\" class=\"wp-image-461\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Ungarelationer1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Ungarelationer1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Ungarelationer.se<\/strong><br>\u062f\u0639\u0645 \u0627\u0644\u0634\u0628\u0627\u0628 \u062d\u062a\u0649 \u0633\u0646 20 \u0639\u0627\u0645\u064b\u0627 \u0627\u0644\u0630\u064a\u0646 \u064a\u062a\u0639\u0631\u0636\u0648\u0646 \u0644\u0644\u0639\u0646\u0641 \u0641\u064a \u0639\u0644\u0627\u0642\u062a\u0647\u0645\u060c \u0633\u0648\u0627\u0621 \u0643\u0627\u0646\u0648\u0627 \u0627\u0644\u062c\u0627\u0646\u064a \u0623\u0648 \u0627\u0644\u0635\u062f\u064a\u0642. \u0642\u0645 \u0628\u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0628\u0634\u0643\u0644 \u0645\u062c\u0647\u0648\u0644 \u0643\u0644 \u0645\u0633\u0627\u0621 \u0628\u064a\u0646 \u0627\u0644\u0633\u0627\u0639\u0629 8-10 \u0645\u0633\u0627\u0621\u064b.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/ungarelationer.se\/chatt\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tilia.png\" alt=\"Bild med texten Tilia\" class=\"wp-image-173\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tilia.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tilia-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062a\u064a\u0644\u064a\u0627<\/strong><br>\u0645\u0646\u0638\u0645\u0629 \u063a\u064a\u0631 \u0631\u0628\u062d\u064a\u0629 \u062a\u0639\u0646\u0649 \u0628\u0627\u0644\u0635\u062d\u0629 \u0627\u0644\u0639\u0642\u0644\u064a\u0629 \u0644\u0644\u0634\u0628\u0627\u0628 \u0648\u0627\u0644\u0634\u0628\u0627\u0628.<br>\u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0648\u0627\u0644\u0628\u0631\u064a\u062f.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:stod@teamtilia.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/teamtilia.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Maskrosbarn2.png\" alt=\"Logotyp Maskrosbarn\" class=\"wp-image-315\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Maskrosbarn2.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Maskrosbarn2-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0623\u0637\u0641\u0627\u0644 \u0627\u0644\u0647\u0646\u062f\u0628\u0627\u0621<\/strong><br>\u0646\u062d\u0646 \u0647\u0646\u0627 \u0645\u0646 \u0623\u062c\u0644\u0643 \u0645\u0645\u0646 \u062a\u062a\u0631\u0627\u0648\u062d \u0623\u0639\u0645\u0627\u0631\u0647\u0645 \u0628\u064a\u0646 13 \u064819 \u0639\u0627\u0645\u064b\u0627 \u0648\u064a\u0634\u0639\u0631\u0648\u0646 \u0628\u0635\u0639\u0648\u0628\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0641\u064a \u0627\u0644\u0645\u0646\u0632\u0644.<br>\u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0648\u0627\u0644\u0642\u064a\u0645 \u0648\u0645\u0631\u0643\u0632 \u0627\u0644\u0634\u0628\u0627\u0628.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/maskrosbarn.org\/aktiviteter-stod\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tryggabarnen.png\" alt=\"Bild med texten Tryggabarnen\" class=\"wp-image-172\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tryggabarnen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Tryggabarnen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0623\u0637\u0641\u0627\u0644 \u062a\u0631\u064a\u062c\u0627<\/strong><br>Trygga Barnen \u0645\u0648\u062c\u0648\u062f \u0645\u0646 \u0623\u062c\u0644\u0643 \u0627\u0644\u0630\u064a\u0646 \u062a\u062a\u0631\u0627\u0648\u062d \u0623\u0639\u0645\u0627\u0631\u0647\u0645 \u0628\u064a\u0646 7 \u064825 \u0639\u0627\u0645\u064b\u0627 \u0648\u0627\u0644\u0630\u064a\u0646 \u0646\u0634\u0623\u0648\u0627 \u0623\u0648 \u0646\u0634\u0623\u0648\u0627 \u0641\u064a \u0639\u0627\u0626\u0644\u0629 \u062a\u0639\u0627\u0646\u064a \u0645\u0646 \u0646\u0648\u0639 \u0645\u0627 \u0645\u0646 \u0627\u0644\u0625\u062f\u0645\u0627\u0646.<br>\u0645\u062d\u0627\u062f\u062b\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.tryggabarnen.org\/kontakt\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-kompis.png\" alt=\"Bild med texten Jourhavande kompis\" class=\"wp-image-306\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-kompis.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-kompis-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u0635\u0644\u064a\u0628 \u0627\u0644\u0623\u062d\u0645\u0631 \u0641\u064a \u0627\u0644\u062e\u062f\u0645\u0629 \u064a\u0627 \u0635\u062f\u064a\u0642\u064a<\/strong><br>\u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0639\u0646\u062f \u0627\u0644\u0637\u0644\u0628 \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u062f\u0631\u062f\u0634\u0629 \u062f\u0639\u0645 \u0645\u062c\u0647\u0648\u0644\u0629 \u0644\u0643 \u062d\u062a\u0649 \u0633\u0646 25 \u0639\u0627\u0645\u064b\u0627. <br>\u0646\u062d\u0646 \u0627\u0644\u0630\u064a\u0646 \u0646\u0648\u0638\u0641 \u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0644\u0633\u0646\u0627 \u0639\u0644\u0645\u0627\u0621 \u0646\u0641\u0633 \u0623\u0648 \u062e\u0628\u0631\u0627\u0621\u060c \u0646\u062d\u0646 \u0641\u0642\u0637 \u0634\u0628\u0627\u0628 \u0645\u0648\u062c\u0648\u062f\u0648\u0646 \u0628\u062c\u0627\u0646\u0628\u0643 \u0639\u0646\u062f\u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0627\u0644\u062a\u062d\u062f\u062b!<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.rkuf.se\/fa-stod\/jourhavande-kompis\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Livslinjen.png\" alt=\"Bild med texten Livslinjen\" class=\"wp-image-307\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Livslinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Livslinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u062d\u064a\u0627\u0629<\/strong><br>\u0647\u0644 \u064a\u062a\u0631\u0627\u0648\u062d \u0639\u0645\u0631\u0643 \u0628\u064a\u0646 16 \u064825 \u0639\u0627\u0645\u064b\u0627 \u0648\u062a\u0631\u063a\u0628 \u0641\u064a \u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0645\u0639 \u0634\u062e\u0635 \u0628\u0627\u0644\u063a\u061f <br>\u0641\u064a Livslinjen\u060c \u0646\u0633\u062a\u0645\u0639 \u0625\u0644\u064a\u0643 \u0648\u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u062d\u062f\u062b \u0639\u0646 \u0645\u0639\u0638\u0645 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0648\u0639\u0646 \u0645\u0634\u0627\u0639\u0631\u0643 \u0648\u0623\u0641\u0643\u0627\u0631\u0643 \u0648\u0639\u0646\u062f\u0645\u0627 \u062a\u0634\u0639\u0631 \u0628\u0623\u0646 \u0627\u0644\u062d\u064a\u0627\u0629 \u0635\u0639\u0628\u0629.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/mind.se\/stod-kunskap\/prata-eller-chatta-med-volontar\/livslinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foreningen-tillsammans1.png\" alt=\"Logotyp f\u00f6r F\u00f6reningen Tillsammans\" class=\"wp-image-381\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foreningen-tillsammans1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foreningen-tillsammans1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u062c\u0645\u0639\u064a\u0629 \u0645\u0639\u0627<\/strong><br>\u0646\u062d\u0646 \u0647\u0646\u0627 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062c\u0645\u064a\u0639 \u0628\u064a\u0646\u0647\u0645\u0627 <br>\u0645\u0646 12 \u0625\u0644\u0649 30 \u0639\u0627\u0645\u064b\u0627 \u0648\u0644\u062f\u064a\u0647\u0645 \u062e\u0628\u0631\u0629 \u0641\u064a \u0627\u0644\u0639\u0646\u0641 \u0627\u0644\u062c\u0646\u0633\u064a. <br>\u0646\u062d\u0646 \u0647\u0646\u0627 \u0623\u064a\u0636\u064b\u0627 \u0645\u0646 \u0623\u062c\u0644\u0643 \u0625\u0630\u0627 \u0643\u0646\u062a \u0642\u0631\u064a\u0628\u064b\u0627 \u0623\u0648 \u0635\u062f\u064a\u0642\u064b\u0627 \u0623\u0648 \u0632\u0645\u064a\u0644\u064b\u0627 \u0644\u0634\u062e\u0635 \u0648\u0642\u0639 \u0636\u062d\u064a\u0629. <br>\u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0627\u0644\u0647\u0648\u064a\u0629 \u0627\u0644\u062c\u0646\u0633\u064a\u0629 \u0623\u0648 \u0627\u0644\u062a\u0648\u062c\u0647 \u0627\u0644\u062c\u0646\u0633\u064a\u060c \u0641\u0646\u062d\u0646 \u0646\u0631\u062d\u0628 \u0628\u0637\u0644\u0628 \u0627\u0644\u062f\u0639\u0645 \u0645\u0646\u0627.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:stod@foreningentillsammans.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.foreningentillsammans.se\/om-vart-stod\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"KVINNA\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinna2-1024x171.png\" alt=\"\" class=\"wp-image-197\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinna2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinna2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinna2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinna2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinnofridslinjen.png\" alt=\"\" class=\"wp-image-123\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinnofridslinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kvinnofridslinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u0633\u0644\u0627\u0645 \u0627\u0644\u0646\u0633\u0627\u0626\u064a<\/strong><br>\u062f\u0639\u0645 \u0627\u0644\u0646\u0633\u0627\u0621 \u0627\u0644\u0644\u0627\u062a\u064a \u062a\u0639\u0631\u0636\u0646 \u0644\u0644\u0639\u0646\u0641 \u0627\u0644\u062c\u0633\u062f\u064a \u0623\u0648 \u0627\u0644\u0646\u0641\u0633\u064a \u0623\u0648 \u0627\u0644\u062c\u0646\u0633\u064a. \u0627\u0644\u0645\u0643\u0627\u0644\u0645\u0629 \u0645\u062c\u0627\u0646\u064a\u0629 \u0648\u0645\u062c\u0647\u0648\u0644\u0629 \u0627\u0644\u0645\u0635\u062f\u0631.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-5050501\/\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/kvinnofridslinjen.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akutmottagning-sos.png\" alt=\"\" class=\"wp-image-268\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akutmottagning-sos.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Akutmottagning-sos-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0642\u0633\u0645 \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0644\u0636\u062d\u0627\u064a\u0627 \u0627\u0644\u0627\u063a\u062a\u0635\u0627\u0628<\/strong><br>\u0633\u0648\u062f\u0631\u0632\u062c\u0648\u062e\u0648\u0633\u064a\u062a.<br>\u0645\u0633\u0627\u0639\u062f\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0644\u0644\u0646\u0633\u0627\u0621 \u0627\u0644\u0644\u0627\u062a\u064a \u062a\u0639\u0631\u0636\u0646 \u0644\u0644\u0627\u063a\u062a\u0635\u0627\u0628.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-12364670\/\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.sodersjukhuset.se\/avdelningar-och-mottagningar\/akutmottagningar\/akutmottagning-for-valdtagna\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alla-kvinnors-hus.png\" alt=\"\" class=\"wp-image-122\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alla-kvinnors-hus.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alla-kvinnors-hus-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0643\u0644 \u0628\u064a\u062a \u0627\u0644\u0646\u0633\u0627\u0621<\/strong><br>\u064a\u0642\u062f\u0645 \u0627\u0644\u062f\u0639\u0645 \u0639\u0628\u0631 \u0627\u0644\u0647\u0627\u062a\u0641 \u0648\u0627\u0644\u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u0645\u062d\u0645\u064a\u0629.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-64409203\/\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/allakvinnorshus.org\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Fempowerment.png\" alt=\"\" class=\"wp-image-275\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Fempowerment.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Fempowerment-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0642\u0648\u0629 \u0627\u0644\u0645\u0631\u0623\u0629<\/strong><br>\u064a\u0642\u062f\u0645 \u0645\u0631\u0643\u0632 \u0627\u0644\u0645\u0631\u0623\u0629 \u0648\u0627\u0644\u062f\u0639\u0645 Fempowerment \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0648\u0627\u0644\u062f\u0639\u0645 \u0648\u0627\u0644\u0645\u0634\u0648\u0631\u0629 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u064a\u0629 \u0628\u0644\u063a\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-339900\/\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/fempowerment.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/ROKS1.png\" alt=\"Logotyp f\u00f6r ROKS\" class=\"wp-image-496\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/ROKS1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/ROKS1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0631\u0648\u0643\u0633<\/strong><br>\u062a\u0642\u0648\u0645 \u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0644\u0645\u0644\u0627\u062c\u0626 \u0627\u0644\u0641\u062a\u064a\u0627\u062a \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0641\u064a \u0627\u0644\u0633\u0648\u064a\u062f \u0628\u062c\u0645\u0639 \u0645\u0644\u0627\u062c\u0626 \u0627\u0644\u0641\u062a\u064a\u0627\u062a \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0628\u0644\u0627\u062f. <br>\u062a\u0642\u0648\u0645 \u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0644\u0644\u0641\u062a\u064a\u0627\u062a \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0641\u064a \u0631\u0648\u0643 \u0628\u062f\u0639\u0645 \u0648\u0645\u0633\u0627\u0639\u062f\u0629 \u0623\u0648\u0644\u0626\u0643 \u0627\u0644\u0630\u064a\u0646 \u064a\u0639\u0631\u0641\u0648\u0646 \u0623\u0646\u0641\u0633\u0647\u0645 \u0639\u0644\u0649 \u0623\u0646\u0647\u0645 \u0641\u062a\u0627\u0629 \u0623\u0648 \u0627\u0645\u0631\u0623\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/roks.se\/fa-stod\/hitta-en-jour\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Terrafem.png\" alt=\"\" class=\"wp-image-294\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Terrafem.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Terrafem-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062a\u064a\u0631\u0627\u0641\u064a\u0645<\/strong><br>\u062a\u0642\u062f\u0645 Terrafem \u0627\u0644\u062f\u0639\u0645 \u0648\u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0648\u0627\u0644\u0645\u0634\u0648\u0631\u0629 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u064a\u0629 \u0644\u0644\u0646\u0633\u0627\u0621 \u0627\u0644\u0645\u0639\u0646\u0641\u0627\u062a \u0628\u0623\u0643\u062b\u0631 \u0645\u0646 70 \u0644\u063a\u0629. \u0646\u0642\u0648\u0645 \u0628\u0647\u0630\u0627 \u0627\u0644\u0639\u0645\u0644 \u0639\u0628\u0631 \u0647\u0627\u062a\u0641 \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0627\u0644\u062e\u0627\u0635 \u0628\u0646\u0627\u060c \u0648\u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u064a\u0629\u060c \u0648\u0645\u0644\u062c\u0623 \u0627\u0644\u0646\u0633\u0627\u0621 \u0648\u062f\u0627\u0631 \u0627\u0644\u0641\u062a\u064a\u0627\u062a.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-521010\/\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/terrafem.org\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Unizon.png\" alt=\"\" class=\"wp-image-296\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Unizon.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Unizon-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0623\u0648\u0646\u064a\u0632\u0648\u0646<\/strong><br>\u062a\u062c\u0645\u0639 Unizon \u0623\u0643\u062b\u0631 \u0645\u0646 140 \u0645\u0644\u062c\u0623 \u0644\u0644\u0646\u0633\u0627\u0621 \u0648\u0645\u0644\u0627\u062c\u0626 \u0644\u0644\u0641\u062a\u064a\u0627\u062a \u0648\u0645\u0644\u0627\u062c\u0626 \u0644\u0644\u0634\u0628\u0627\u0628 \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0628\u0644\u0627\u062f. \u0646\u062d\u0646 \u0646\u062f\u0639\u0645\u0643 \u0648\u0646\u0633\u062a\u0645\u0639 \u0625\u0644\u064a\u0643 \u0648\u0646\u0635\u062f\u0642\u0643. \u0627\u0644\u062f\u0639\u0645 \u0645\u062c\u0627\u0646\u064a \u0648\u0644\u064a\u0633 \u0639\u0644\u064a\u0643 \u0623\u0646 \u062a\u062e\u0628\u0631\u0646\u0627 \u0645\u0646 \u0623\u0646\u062a.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.unizonjourer.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"MAN\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Man2-1024x171.png\" alt=\"\" class=\"wp-image-198\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Man2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Man2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Man2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Man2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mansjouren.png\" alt=\"\" class=\"wp-image-126\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mansjouren.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Mansjouren-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u063a\u0631\u0641\u0629 \u0637\u0648\u0627\u0631\u0626 \u0627\u0644\u0631\u062c\u0627\u0644<\/strong><br>\u062f\u0639\u0645 \u0627\u0644\u0631\u062c\u0627\u0644 \u0627\u0644\u0630\u064a\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0645\u0631\u0636 \u0639\u0642\u0644\u064a \u0623\u0648 \u064a\u062a\u0639\u0631\u0636\u0648\u0646 \u0644\u0644\u0639\u0646\u0641.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-555666\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:info@mansjouren.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.mansjouren.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/stodlinjen-for-man.png\" alt=\"\" class=\"wp-image-127\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/stodlinjen-for-man.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/stodlinjen-for-man-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u062f\u0639\u0645 \u0644\u0644\u0631\u062c\u0627\u0644<\/strong><br>\u0644\u0644\u0631\u062c\u0627\u0644 \u0627\u0644\u0630\u064a\u0646 \u062a\u0639\u0631\u0636\u0648\u0627 \u0644\u0644\u062a\u0647\u062f\u064a\u062f\u0627\u062a \u0648\u0627\u0644\u0639\u0646\u0641 \u0641\u064a \u0627\u0644\u0639\u0644\u0627\u0642\u0627\u062a \u0627\u0644\u0648\u062b\u064a\u0642\u0629.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-8080803\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/stodlinjenforman.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/01\/Under-kevlaret2.png\" alt=\"Bild med texten Under kevlaret\" class=\"wp-image-668\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/01\/Under-kevlaret2.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/01\/Under-kevlaret2-300x86.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/01\/Under-kevlaret2-18x5.png 18w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/01\/Under-kevlaret2-350x100.png 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062a\u062d\u062a \u0643\u064a\u0641\u0644\u0631<\/strong><br>\u0641\u064a Under the Kevlaret\u060c \u064a\u0645\u0643\u0646\u0643 \u0643\u0631\u062c\u0644 \u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0645\u0639 \u0645\u062a\u0637\u0648\u0639\u064a\u0646\u0627 \u062d\u0648\u0644 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u062a\u064a \u0646\u0627\u062f\u0631\u064b\u0627 \u0645\u0627 \u062a\u062a\u062d\u062f\u062b \u0639\u0646\u0647\u0627 \u0645\u0639 \u0627\u0644\u0622\u062e\u0631\u064a\u0646\u060c \u0623\u0648 \u0627\u0644\u0627\u0646\u0636\u0645\u0627\u0645 \u0625\u0644\u0649 \u0645\u062c\u062a\u0645\u0639\u0646\u0627 \u0639\u0644\u0649 Discord \u0648\u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0645\u0639 \u0634\u0628\u0627\u0628 \u0622\u062e\u0631\u064a\u0646.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:hej@underkevlaret.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.underkevlaret.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a class=\"ub_icon_wrapper\" href=\"https:\/\/discord.com\/invite\/Ea68437GVQ\" target=\"_blank\" rel=\"noopener\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path d=\"M524.531,69.836a1.5,1.5,0,0,0-.764-.7A485.065,485.065,0,0,0,404.081,32.03a1.816,1.816,0,0,0-1.923.91,337.461,337.461,0,0,0-14.9,30.6,447.848,447.848,0,0,0-134.426,0,309.541,309.541,0,0,0-15.135-30.6,1.89,1.89,0,0,0-1.924-.91A483.689,483.689,0,0,0,116.085,69.137a1.712,1.712,0,0,0-.788.676C39.068,183.651,18.186,294.69,28.43,404.354a2.016,2.016,0,0,0,.765,1.375A487.666,487.666,0,0,0,176.02,479.918a1.9,1.9,0,0,0,2.063-.676A348.2,348.2,0,0,0,208.12,430.4a1.86,1.86,0,0,0-1.019-2.588,321.173,321.173,0,0,1-45.868-21.853,1.885,1.885,0,0,1-.185-3.126c3.082-2.309,6.166-4.711,9.109-7.137a1.819,1.819,0,0,1,1.9-.256c96.229,43.917,200.41,43.917,295.5,0a1.812,1.812,0,0,1,1.924.233c2.944,2.426,6.027,4.851,9.132,7.16a1.884,1.884,0,0,1-.162,3.126,301.407,301.407,0,0,1-45.89,21.83,1.875,1.875,0,0,0-1,2.611,391.055,391.055,0,0,0,30.014,48.815,1.864,1.864,0,0,0,2.063.7A486.048,486.048,0,0,0,610.7,405.729a1.882,1.882,0,0,0,.765-1.352C623.729,277.594,590.933,167.465,524.531,69.836ZM222.491,337.58c-28.972,0-52.844-26.587-52.844-59.239S193.056,219.1,222.491,219.1c29.665,0,53.306,26.82,52.843,59.239C275.334,310.993,251.924,337.58,222.491,337.58Zm195.38,0c-28.971,0-52.843-26.587-52.843-59.239S388.437,219.1,417.871,219.1c29.667,0,53.307,26.82,52.844,59.239C470.715,310.993,447.538,337.58,417.871,337.58Z\"><\/path><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"HBTQIA\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/HBTQIA-1024x171.png\" alt=\"\" class=\"wp-image-391\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/HBTQIA-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/HBTQIA-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/HBTQIA-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/HBTQIA.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Regnbagslinjen1.png\" alt=\"Logotyp f\u00f6r Regnb\u00e5gslinjen\" class=\"wp-image-380\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Regnbagslinjen1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Regnbagslinjen1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0642\u0648\u0633 \u0642\u0632\u062d<\/strong><br>\u062e\u0637 \u0642\u0648\u0633 \u0642\u0632\u062d \u0647\u0648 \u062e\u0637 \u0633\u0627\u062e\u0646 \u064a\u0645\u0643\u0646\u0643 \u0645\u0646 \u062e\u0644\u0627\u0644\u0647 \u0643\u0634\u062e\u0635 \u0645\u0646 \u0645\u062c\u062a\u0645\u0639 LGBTQIA+ \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0623\u0648 \u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u062d\u0648\u0644 \u0623\u064a \u0634\u064a\u0621 \u064a\u062b\u0642\u0644 \u0643\u0627\u0647\u0644\u0643.<br>\u0646\u062d\u0646 \u0627\u0644\u0630\u064a\u0646 \u0646\u062c\u064a\u0628 \u0647\u0645 HBTQIA+.<br>\u0639\u0644\u064a\u0643 \u0623\u0646 \u062a\u0642\u0631\u0631 \u0645\u0627 \u062a\u0631\u064a\u062f \u0627\u0644\u062a\u062d\u062f\u062b \u0639\u0646\u0647.<br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +46770-550010\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/kyrkanssos.se\/hitta-hjalp\/regnbagslinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Stod-for-transpersoner.png\" alt=\"Bild med texten St\u00f6d f\u00f6r transpersoner\" class=\"wp-image-321\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Stod-for-transpersoner.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Stod-for-transpersoner-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u062f\u0639\u0645 \u0644\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0645\u062a\u062d\u0648\u0644\u064a\u0646 \u062c\u0646\u0633\u064a\u0627<\/strong><br>\u062e\u0637 \u062f\u0639\u0645 \u0644\u0644\u0628\u0627\u0644\u063a\u064a\u0646 \u0627\u0644\u0645\u062a\u062d\u0648\u0644\u064a\u0646 \u062c\u0646\u0633\u064a\u064b\u0627\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u063a\u064a\u0631 \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u064a\u0646\u060c \u0627\u0644\u0630\u064a\u0646 \u062a\u0639\u0631\u0636\u0648\u0627 \u0644\u0639\u0646\u0641 \u0627\u0644\u0634\u0631\u064a\u0643 \u0627\u0644\u062d\u0645\u064a\u0645 \u0623\u0648 \u0627\u0644\u0627\u0639\u062a\u062f\u0627\u0621 \u0627\u0644\u062c\u0646\u0633\u064a.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-550000\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/stodlinjenfortranspersoner.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSL.png\" alt=\"\" class=\"wp-image-322\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSL.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSL-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>RFSL<\/strong><br>\u062a\u0642\u062f\u0645 RFSL \u0627\u0644\u062f\u0639\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0645\u0643\u0627\u0644\u0645\u0627\u062a \u0641\u064a \u0627\u0644\u0645\u0648\u0642\u0639 \u0623\u0648 \u0627\u0644\u0645\u0643\u0627\u0644\u0645\u0627\u062a \u0627\u0644\u0647\u0627\u062a\u0641\u064a\u0629 \u0623\u0648 \u0645\u0643\u0627\u0644\u0645\u0627\u062a \u0627\u0644\u0641\u064a\u062f\u064a\u0648 \u0623\u0648 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a. <br>\u0627\u0644\u0645\u0643\u0627\u0644\u0645\u0627\u062a \u0648\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0623\u062e\u0631\u0649 \u0645\u062c\u0627\u0646\u064a\u0629 \u0648\u0639\u0644\u0649 \u0627\u0644\u0645\u0648\u0638\u0641\u064a\u0646 \u0648\u0627\u062c\u0628 \u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0627\u0644\u0633\u0631\u064a\u0629. <br>\u064a\u0645\u0643\u0646\u0643 \u0623\u0646 \u062a\u0638\u0644 \u0645\u062c\u0647\u0648\u0644 \u0627\u0644\u0647\u0648\u064a\u0629 \u0639\u0646\u062f \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u0646\u0627.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"tel:+4620%E2%80%93341316\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:stod@rfsl.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.rfsl.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"SENIOR\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Senior-1024x171.png\" alt=\"\" class=\"wp-image-272\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Senior-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Senior-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Senior-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Senior.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Aldrelinjen.png\" alt=\"\" class=\"wp-image-274\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Aldrelinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Aldrelinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u062e\u0637 \u0627\u0644\u0623\u0642\u062f\u0645<\/strong><br>\u0647\u0644 \u062a\u0634\u062a\u0627\u0642 \u0644\u0634\u062e\u0635 \u0645\u0627 \u0644\u062a\u062a\u062d\u062f\u062b \u0645\u0639\u0647\u061f \u0646\u062d\u0646 \u0639\u0644\u0649 \u0628\u0639\u062f \u0645\u0643\u0627\u0644\u0645\u0629 \u0647\u0627\u062a\u0641\u064a\u0629 \u0641\u0642\u0637.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-222233\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/mind.se\/stod-kunskap\/prata-eller-chatta-med-volontar\/aldrelinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"F\u00d6R\u00c4LDER\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foralder2-1024x171.png\" alt=\"\" class=\"wp-image-199\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foralder2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foralder2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foralder2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foralder2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foraldralinjen.png\" alt=\"\" class=\"wp-image-134\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foraldralinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Foraldralinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u062e\u0637 \u0627\u0644\u0623\u0628\u0648\u064a<\/strong><br>\u0644\u0644\u0622\u0628\u0627\u0621 \u0627\u0644\u0630\u064a\u0646 \u064a\u0634\u0639\u0631\u0648\u0646 \u0628\u0627\u0644\u0642\u0644\u0642 \u0639\u0644\u0649 \u0637\u0641\u0644\u0647\u0645 \u0623\u0648 \u0637\u0641\u0644 \u0642\u0631\u064a\u0628 \u0645\u0646\u0647\u0645.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-852000\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/mind.se\/stod-kunskap\/prata-eller-chatta-med-volontar\/foraldralinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Radda-Barnen-Foralder.png\" alt=\"\" class=\"wp-image-132\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Radda-Barnen-Foralder.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Radda-Barnen-Foralder-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0647\u0627\u062a\u0641 \u0627\u0644\u0648\u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u062e\u0627\u0635 \u0628\u0645\u0646\u0638\u0645\u0629 \u0625\u0646\u0642\u0627\u0630 \u0627\u0644\u0637\u0641\u0648\u0644\u0629<\/strong><br>\u0627\u0644\u062f\u0639\u0645 \u0648\u0627\u0644\u0645\u0634\u0648\u0631\u0629 \u0644\u0644\u0622\u0628\u0627\u0621 \u0648\u0627\u0644\u0623\u0645\u0647\u0627\u062a.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-7867861\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.raddabarnen.se\/rad-och-kunskap\/foralder\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BRIS-Vuxentelefon.png\" alt=\"\" class=\"wp-image-133\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BRIS-Vuxentelefon.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/BRIS-Vuxentelefon-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>BRIS \u2013 \u0647\u0627\u062a\u0641 \u0644\u0644\u0628\u0627\u0644\u063a\u064a\u0646<\/strong><br>\u0644\u0644\u0628\u0627\u0644\u063a\u064a\u0646 \u0627\u0644\u0630\u064a\u0646 \u0644\u062f\u064a\u0647\u0645 \u0623\u0633\u0626\u0644\u0629 \u0623\u0648 \u0645\u062e\u0627\u0648\u0641 \u0628\u0634\u0623\u0646 \u0627\u0644\u0623\u0637\u0641\u0627\u0644.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4677-15050501\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.bris.se\/for-vuxna\/stod-och-rad\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"F\u00d6R-ALLA\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/For-alla2-1024x171.png\" alt=\"\" class=\"wp-image-200\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/For-alla2-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/For-alla2-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/For-alla2-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/For-alla2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Sjukvardsradgivning.png\" alt=\"\" class=\"wp-image-143\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Sjukvardsradgivning.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Sjukvardsradgivning-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>1177<\/strong><br>1177 \u0647\u0648 \u0631\u0642\u0645 \u0627\u0644\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0627\u0644\u0635\u062d\u064a\u0629. <br>\u0627\u062a\u0635\u0644 \u0628\u0627\u0644\u0631\u0642\u0645 1177 \u0625\u0630\u0627 \u0645\u0631\u0636\u062a \u0623\u0646\u062a \u0623\u0648 \u0623\u062d\u062f \u0623\u0642\u0627\u0631\u0628\u0643 \u0648\u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0645\u0645\u0631\u0636\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: 1177\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.1177.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Brottsofferjouren.png\" alt=\"\" class=\"wp-image-144\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Brottsofferjouren.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Brottsofferjouren-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u062e\u0637 \u0627\u0644\u0633\u0627\u062e\u0646 \u0644\u0636\u062d\u0627\u064a\u0627 \u0627\u0644\u062c\u0631\u064a\u0645\u0629<\/strong><br>\u062f\u0639\u0645 \u0636\u062d\u0627\u064a\u0627 \u0627\u0644\u062c\u0631\u064a\u0645\u0629 \u0648\u0627\u0644\u0634\u0647\u0648\u062f \u0648\u0627\u0644\u0623\u0642\u0627\u0631\u0628.<br><br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0647\u0627\u062a\u0641: 116006\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.brottsofferjouren.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Nationell-Information.png\" alt=\"\" class=\"wp-image-145\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Nationell-Information.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Nationell-Information-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>113 13<\/strong><br>113 13 \u0647\u0648 \u0631\u0642\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0648\u0637\u0646\u064a \u0641\u064a \u0627\u0644\u0633\u0648\u064a\u062f. \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0648\u062c\u0647 \u0647\u0646\u0627 \u0644\u0625\u0639\u0637\u0627\u0621 \u0648\u062a\u0644\u0642\u064a \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u062d\u0648\u0644 \u0627\u0644\u062d\u0648\u0627\u062f\u062b \u0648\u0627\u0644\u0623\u0632\u0645\u0627\u062a \u0627\u0644\u0643\u0628\u0631\u0649.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0647\u0627\u062a\u0641: 11313\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.sosalarm.se\/112-och-andra-viktiga-nummer\/viktiga-nummer\/11313\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Polismyndigheten.png\" alt=\"\" class=\"wp-image-146\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Polismyndigheten.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Polismyndigheten-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>114 14<\/strong><br>114 14 \u0647\u0648 \u0631\u0642\u0645 \u0627\u0644\u0645\u0633\u0627\u0626\u0644 \u0627\u0644\u0634\u0631\u0637\u064a\u0629 \u063a\u064a\u0631 \u0627\u0644\u0639\u0627\u062c\u0644\u0629. \u0627\u062a\u0635\u0644 \u0628\u0627\u0644\u0631\u0642\u0645 14 114 \u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u062c\u0631\u0627\u0626\u0645 \u0648\u0627\u0644\u0623\u062d\u062f\u0627\u062b \u063a\u064a\u0631 \u0627\u0644\u0645\u0633\u062a\u0645\u0631\u0629 \u0623\u0648 \u0627\u0644\u0639\u0627\u062c\u0644\u0629.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0647\u0627\u062a\u0641: 11414\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/polisen.se\/om-polisen\/kontakt\/polisens-telefonnummer\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Journummer-forsvunna-barn.png\" alt=\"\" class=\"wp-image-147\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Journummer-forsvunna-barn.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Journummer-forsvunna-barn-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>116 000<\/strong><br>\u0631\u0642\u0645 \u0627\u0644\u0637\u0648\u0627\u0631\u0626 \u0627\u0644\u0645\u0634\u062a\u0631\u0643 \u0644\u0644\u0627\u062a\u062d\u0627\u062f \u0627\u0644\u0623\u0648\u0631\u0648\u0628\u064a \u0644\u0644\u0625\u0628\u0644\u0627\u063a \u0639\u0646 \u0627\u0644\u0623\u0637\u0641\u0627\u0644 \u0627\u0644\u0645\u0641\u0642\u0648\u062f\u064a\u0646.<br><br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0647\u0627\u062a\u0641: 116000\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.sosalarm.se\/112-och-andra-viktiga-nummer\/viktiga-nummer\/116000\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-Medmanniska.png\" alt=\"\" class=\"wp-image-174\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-Medmanniska.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Jourhavande-Medmanniska-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0632\u0645\u064a\u0644 \u062a\u062d\u062a \u0627\u0644\u0637\u0644\u0628<\/strong><br>\u0646\u062d\u0646 \u0645\u0648\u062c\u0648\u062f\u0648\u0646 \u0645\u0646 \u0623\u062c\u0644\u0643 \u0625\u0630\u0627 \u0643\u0646\u062a \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0634\u062e\u0635 \u0645\u0627 \u0644\u0644\u062a\u062d\u062f\u062b \u0645\u0639\u0647\u060c \u0634\u062e\u0635 \u064a\u0633\u062a\u0645\u0639 \u0625\u0644\u064a\u0643 \u062e\u0644\u0627\u0644 \u0648\u0642\u062a \u0627\u0644\u0646\u0647\u0627\u0631 \u0639\u0646\u062f\u0645\u0627 \u0644\u0627 \u064a\u0643\u0648\u0646 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u0645\u0633\u062a\u064a\u0642\u0638\u064a\u0646. <br>\u0627\u0644\u0645\u062d\u0627\u062f\u062b\u0629 \u0645\u062c\u0647\u0648\u0644\u0629 \u062a\u0645\u0627\u0645\u0627.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-7021680\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.jourhavande-medmanniska.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anhoriglinjen1.png\" alt=\"\" class=\"wp-image-388\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anhoriglinjen1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anhoriglinjen1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u0627\u0642\u0627\u0631\u0628<\/strong><br>\u0642\u0631\u064a\u0628 \u064a\u0639\u0646\u064a \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0630\u064a \u064a\u0639\u062a\u0646\u064a \u0623\u0648 \u064a\u0633\u0627\u0639\u062f \u0623\u0648 \u064a\u062f\u0639\u0645 \u0642\u0631\u064a\u0628 \u064a\u062d\u062a\u0627\u062c \u0625\u0644\u064a\u0647 \u0628\u0633\u0628\u0628 \u0645\u0631\u0636 \u062c\u0633\u062f\u064a \u0623\u0648 \u0639\u0642\u0644\u064a \u0623\u0648 \u0627\u0644\u0633\u0646 \u0623\u0648 \u0627\u0644\u0625\u0639\u0627\u0642\u0629.<br><br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +46200-239500\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"mailto:info@anhoriglinjen.se\" class=\"ub_icon_wrapper\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 71.9\" style=\"enable-background:new 0 0 122.88 71.9\" xml:space=\"preserve\"><g><path d=\"M29.56,0h88.02c1.57,0,2.95,0.64,3.9,1.67c0.96,1.03,1.5,2.46,1.38,4.03l-4.42,60.49c-0.09,1.18-0.53,2.28-1.22,3.2 c-0.14,0.3-0.33,0.57-0.59,0.8c-0.17,0.15-0.36,0.28-0.56,0.37c-1.05,0.83-2.36,1.33-3.74,1.33l-88.02,0 c-1.57,0-2.95-0.64-3.91-1.67c-0.96-1.03-1.49-2.46-1.38-4.03l1.25-10.18h4.37l-1.08,7.78l0,0l33.11-30.93L27.67,7.72l-0.29,3.93 H23l0.43-5.95c0.11-1.57,0.86-3,1.97-4.03C26.51,0.64,27.99,0,29.56,0L29.56,0L29.56,0z M2.19,49.78C0.98,49.78,0,48.8,0,47.59 c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,49.78z M13.02,36.22 c-1.21,0-2.19-0.98-2.19-2.19c0-1.21,0.98-2.19,2.19-2.19h25.06c1.21,0,2.19,0.98,2.19,2.19c0,1.21-0.98,2.19-2.19,2.19H13.02 L13.02,36.22z M2.19,22.66C0.98,22.66,0,21.68,0,20.47c0-1.21,0.98-2.19,2.19-2.19h28.89c1.21,0,2.19,0.98,2.19,2.19 c0,1.21-0.98,2.19-2.19,2.19H2.19L2.19,22.66z M59.87,35.64L25.74,67.52h85.53L83.2,35.64l-10.64,8.54l0,0 c-0.83,0.67-2.01,0.71-2.8,0.03L59.87,35.64L59.87,35.64L59.87,35.64z M86.74,32.81l27.5,31.23l4.13-56.6L86.74,32.81L86.74,32.81 L86.74,32.81z M30.71,4.37l40.73,35.31l44.03-35.31H30.71L30.71,4.37L30.71,4.37z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/anhorigasriksforbund.se\/anhoriglinjen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Preventell.png\" alt=\"\" class=\"wp-image-320\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Preventell.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Preventell-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0628\u0631\u064a\u0641\u064a\u0646\u062a\u064a\u0644<\/strong> <br>PrevenTell \u0647\u0648 \u062e\u0637 \u0645\u0633\u0627\u0639\u062f\u0629 \u0648\u0637\u0646\u064a \u0644\u0645\u0646 \u064a\u0634\u0639\u0631\u0648\u0646 \u0623\u0646\u0647\u0645 \u0641\u0642\u062f\u0648\u0627 \u0627\u0644\u0633\u064a\u0637\u0631\u0629 \u0639\u0644\u0649 \u062d\u064a\u0627\u062a\u0647\u0645 \u0627\u0644\u062c\u0646\u0633\u064a\u0629\u060c \u0623\u0648 \u0627\u0644\u0630\u064a\u0646 \u0642\u062f \u064a\u0634\u0639\u0631\u0648\u0646 \u0628\u0627\u0644\u0642\u0644\u0642 \u0628\u0634\u0623\u0646 \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0648\u0627\u0644\u0623\u0641\u0639\u0627\u0644\u060c \u0623\u0648 \u0627\u0644\u0630\u064a\u0646 \u064a\u062e\u0627\u0641\u0648\u0646 \u0645\u0646 \u0625\u064a\u0630\u0627\u0621 \u0623\u0646\u0641\u0633\u0647\u0645 \u0623\u0648 \u0627\u0644\u0622\u062e\u0631\u064a\u0646.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-667788\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"http:\/\/preventell.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kyrkans-SOS.png\" alt=\"\" class=\"wp-image-399\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kyrkans-SOS.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Kyrkans-SOS-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 SOS<\/strong><br>\u062e\u0637 SOS \u2013 \u0644\u0644\u062c\u0645\u064a\u0639\u060c \u0643\u0644 \u064a\u0648\u0645\u060c \u062d\u062a\u0649 \u0642\u0628\u0644 \u062d\u0644\u0648\u0644 \u0627\u0644\u0638\u0644\u0627\u0645. <br>\u0646\u062d\u0646 \u0647\u0646\u0627 \u0645\u0646 \u0623\u062c\u0644\u0643 \u0639\u0646\u062f\u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0645\u0634\u0627\u0631\u0643\u0629 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u0635\u0639\u0628\u0629 \u0641\u064a \u0627\u0644\u062d\u064a\u0627\u0629 \u0645\u0639 \u0634\u062e\u0635 \u0645\u0627.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +46771-800650\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/kyrkanssos.se\/hitta-hjalp\/sos-telefonen\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Atstorningslinjen.png\" alt=\"Bild med texten \u00c4tst\u00f6rningslinjen\" class=\"wp-image-336\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Atstorningslinjen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Atstorningslinjen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0623\u0643\u0644<\/strong>, <strong>\u0637\u0627\u0632\u062c\u0629 \u0648\u0645\u062c\u0627\u0646\u064a\u0629<\/strong><br>\u0647\u0644 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0634\u062e\u0635 \u0645\u0627 \u0644\u0644\u062a\u062d\u062f\u062b \u0645\u0639\u0647\u061f \u0647\u0644 \u0644\u062f\u064a\u0643 \u0623\u0641\u0643\u0627\u0631 \u062d\u0648\u0644 \u0627\u0644\u062c\u0633\u0645 \u0648\u0627\u0644\u0637\u0639\u0627\u0645 \u0648\u0627\u0644\u062a\u0645\u0627\u0631\u064a\u0646 \u0627\u0644\u0631\u064a\u0627\u0636\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0634\u0639\u0631\u0643 \u0628\u0627\u0644\u0627\u0646\u0632\u0639\u0627\u062c\u061f <br>\u0627\u062a\u0635\u0644 \u0628\u062e\u0637 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0623\u0643\u0644 \u0627\u0644\u062e\u0627\u0635 \u0628\u0646\u0627 \u0648\u062a\u062d\u062f\u062b \u0625\u0644\u0649 \u0634\u062e\u0635 \u0644\u062f\u064a\u0647 \u062a\u062c\u0631\u0628\u062a\u0647 \u0627\u0644\u062e\u0627\u0635\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0646\u0627\u0629 \u0633\u0627\u0628\u0642\u064b\u0627 \u0645\u0646 \u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0623\u0643\u0644.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"tel:+4620%E2%80%93208018\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.friskfri.se\/fa-stod\/telefonlinjer\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Sjalvskadechatten1.png\" alt=\"\" class=\"wp-image-445\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Sjalvskadechatten1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/12\/Sjalvskadechatten1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062f\u0631\u062f\u0634\u0629 \u0625\u064a\u0630\u0627\u0621 \u0627\u0644\u0646\u0641\u0633\u060c \u0634\u064a\u062f\u0648<\/strong><br>\u0647\u0644 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0634\u062e\u0635 \u0645\u0627 \u0644\u0644\u062a\u062d\u062f\u062b \u0645\u0639\u0647 \u062d\u0648\u0644 \u0625\u064a\u0630\u0627\u0621 \u0627\u0644\u0646\u0641\u0633 \u0623\u0648 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0623\u0643\u0644 \u0623\u0648 \u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0633\u0644\u0648\u0643\u064a\u0627\u062a \u0627\u0644\u062a\u062f\u0645\u064a\u0631 \u0627\u0644\u0630\u0627\u062a\u064a\u061f <br>\u0647\u0644 \u0623\u0646\u062a \u0646\u0641\u0633\u0643 \u0645\u062a\u0623\u062b\u0631\u060c \u0623\u0645 \u0623\u0646\u0643 \u0643\u0623\u062d\u062f \u0623\u0642\u0631\u0628\u0627\u0626\u0643 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0627\u0644\u062f\u0639\u0645\u061f<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/sjalvskadechatten.shedo.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSU.png\" alt=\"Bild med texten RFSU\" class=\"wp-image-323\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSU.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/RFSU-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>RFSU<\/strong><br>\u0647\u0646\u0627 \u064a\u0645\u0643\u0646\u0643 \u0637\u0631\u062d \u0627\u0644\u0623\u0633\u0626\u0644\u0629 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u062c\u0633\u062f \u0648\u0627\u0644\u062c\u0646\u0633 \u0648\u0627\u0644\u0639\u0644\u0627\u0642\u0627\u062a. <br>\u0646\u062d\u0646 \u0627\u0644\u0630\u064a\u0646 \u0646\u062c\u064a\u0628 \u0647\u0645 \u0627\u0644\u0642\u0627\u0628\u0644\u0627\u062a \u0648\u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u062c\u0646\u0633 \u0648\u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0646\u0641\u0633. <br>\u0623\u0646\u062a \u0645\u062c\u0647\u0648\u0644 \u062a\u0645\u0627\u0645\u064b\u0627 \u0639\u0646\u062f \u0627\u0644\u062f\u0631\u062f\u0634\u0629. <br>\u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0643\u062a\u0627\u0628\u0629 \u0628\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0633\u0648\u064a\u062f\u064a\u0629 \u0623\u0648 \u0627\u0644\u0625\u0646\u062c\u0644\u064a\u0632\u064a\u0629.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.rfsu.se\/sex-och-relationer\/for-dig-som-undrar\/rfsu-chatten\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2025\/02\/Medicininstruktioner1.png\" alt=\"Bild med texten Medicininstruktioner.se\" class=\"wp-image-765\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062a\u0639\u0644\u064a\u0645\u0627\u062a \u0627\u0644\u062f\u0648\u0627\u0621<\/strong><br>\u0646\u0633\u0627\u0639\u062f \u0627\u0644\u0646\u0627\u0633 \u0639\u0644\u0649 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0623\u062f\u0648\u064a\u0629 \u0628\u0634\u0643\u0644 \u0635\u062d\u064a\u062d!<br>Medicininstruktioner.se \u0647\u064a \u0623\u0643\u0628\u0631 \u0645\u0646\u0635\u0629 \u0641\u064a \u0627\u0644\u0633\u0648\u064a\u062f \u062a\u062d\u062a\u0648\u064a \u0639\u0644\u0649 \u0645\u0642\u0627\u0637\u0639 \u0641\u064a\u062f\u064a\u0648 \u062a\u0639\u0644\u064a\u0645\u064a\u0629 \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0635\u062d\u064a\u062d \u0644\u0644\u0623\u062f\u0648\u064a\u0629 \u0648\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0637\u0628\u064a\u0629.<br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.medicininstruktioner.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"Alkohol\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkohol-droger-1024x171.png\" alt=\"\" class=\"wp-image-276\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkohol-droger-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkohol-droger-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkohol-droger-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkohol-droger.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkoholhjalpen.png\" alt=\"\" class=\"wp-image-277\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkoholhjalpen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Alkoholhjalpen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0645\u0633\u0627\u0639\u062f\u0627\u062a \u0627\u0644\u0643\u062d\u0648\u0644<\/strong><br>\u0647\u0644 \u062a\u0641\u0643\u0631 \u0641\u064a \u0639\u0627\u062f\u0627\u062a \u0627\u0644\u0634\u0631\u0628 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0623\u0648 \u0628\u0634\u062e\u0635 \u0622\u062e\u0631\u061f \u0647\u0644 \u062a\u0631\u064a\u062f \u0625\u062c\u0631\u0627\u0621 \u062a\u063a\u064a\u064a\u0631\u061f<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-844448\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/alkoholhjalpen.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Droghjalpen.png\" alt=\"\" class=\"wp-image-278\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Droghjalpen.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Droghjalpen-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0627\u0644\u062f\u0648\u0627\u0626\u064a\u0629<\/strong><br>\u0646\u062d\u0646 \u0646\u0642\u062f\u0645 \u062f\u0639\u0645\u064b\u0627 \u0645\u062c\u0647\u0648\u0644\u0627\u064b \u0644\u0643 \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0641\u0643\u0631 \u0641\u064a \u062a\u0639\u0627\u0637\u064a\u0643 \u0623\u0648 \u062a\u0639\u0627\u0637\u064a \u0634\u062e\u0635 \u0622\u062e\u0631 \u0644\u0644\u0645\u062e\u062f\u0631\u0627\u062a.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"tel:+4620%E2%80%93919191\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/droghjalpen.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-alkoholister.png\" alt=\"\" class=\"wp-image-279\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-alkoholister.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-alkoholister-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0645\u062f\u0645\u0646\u064a \u0627\u0644\u0643\u062d\u0648\u0644 \u0627\u0644\u0645\u062c\u0647\u0648\u0644\u064a\u0646<\/strong><br>\u0647\u0644 \u062a\u0634\u0639\u0631 \u0623\u0646 \u0627\u0644\u0643\u062d\u0648\u0644 \u0623\u0635\u0628\u062d \u0645\u0634\u0643\u0644\u0629 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0643 \u0623\u0648 \u0644\u0635\u062f\u064a\u0642\u0643\u061f <br>\u0647\u0646\u0627 \u0633\u0648\u0641 \u062a\u062c\u062f \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0648\u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-7203842\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.aa.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-narkomaner.png\" alt=\"\" class=\"wp-image-280\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-narkomaner.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Anonyma-narkomaner-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a \u0627\u0644\u0645\u062c\u0647\u0648\u0644\u0629<\/strong><br>\u0625\u0630\u0627 \u0634\u0639\u0631\u062a \u0623\u0646 \u0644\u062f\u064a\u0643 \u0645\u0634\u0643\u0644\u0629 \u0645\u0639 \u0627\u0644\u0645\u062e\u062f\u0631\u0627\u062a\u060c \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u062e\u0637 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0627\u0644\u062e\u0627\u0635 \u0628\u0646\u0627\u060c \u0648\u0627\u0644\u0630\u064a \u064a\u0639\u0645\u0644 \u0641\u064a\u0647 \u0623\u0639\u0636\u0627\u0621 \u0645\u0646 \u0632\u0645\u0627\u0644\u0629 \u0627\u0644\u0645\u062f\u0645\u0646\u064a\u0646 \u0627\u0644\u0645\u062c\u0647\u0648\u0644\u064a\u0646 (NARCotics Anonymous) \u064a\u0648\u0645\u064a\u064b\u0627.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4677-1138000\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.nasverige.org\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-rounded\" id=\"Spel\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-1024x171.png\" alt=\"\" class=\"wp-image-342\" style=\"box-shadow:var(--wp--preset--shadow--natural)\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-1024x171.png 1024w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-300x50.png 300w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-768x128.png 768w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e35d3e13 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px;border-radius:0px\">\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SpelFriheten1.png\" alt=\"\" class=\"wp-image-376\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SpelFriheten1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/SpelFriheten1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062d\u0631\u064a\u0629 \u0627\u0644\u0644\u0639\u0628<\/strong><br>\u062e\u0637 \u0645\u0633\u0627\u0639\u062f\u0629 Game Freedom \u0645\u0641\u062a\u0648\u062d \u0639\u0644\u0649 \u0645\u062f\u0627\u0631 \u0627\u0644\u0633\u0627\u0639\u0629 \u0637\u0648\u0627\u0644 \u0623\u064a\u0627\u0645 \u0627\u0644\u0623\u0633\u0628\u0648\u0639 \u0639\u0644\u0649 \u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 08-37 43 00. <br>\u064a\u0645\u0643\u0646\u0643 \u0623\u064a\u0636\u064b\u0627 \u0627\u0644\u062f\u0631\u062f\u0634\u0629 \u0645\u0639 \u0645\u062f\u0645\u0646 \u0627\u0644\u0642\u0645\u0627\u0631 \u0627\u0644\u0633\u0627\u0628\u0642 \u0623\u0648 \u062d\u0636\u0648\u0631 \u0627\u062c\u062a\u0645\u0627\u0639\u0627\u062a \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0627\u0644\u0630\u0627\u062a\u064a\u0629 \u0627\u0644\u0645\u062c\u0627\u0646\u064a\u0629. <br>\u062a\u0648\u0641\u0631 \u062d\u0631\u064a\u0629 \u0627\u0644\u0644\u0639\u0628\u0629 \u0623\u064a\u0636\u064b\u0627 \u0627\u0644\u062f\u0639\u0645 \u0644\u0644\u0623\u0642\u0627\u0631\u0628.<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +468-374300\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/www.spelfriheten.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#e3f2f2;border-width:1px;border-radius:5px;padding-top:0;padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0;box-shadow:var(--wp--preset--shadow--natural)\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"172\" src=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-och-anhorig1.png\" alt=\"\" class=\"wp-image-378\" srcset=\"https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-och-anhorig1.png 600w, https:\/\/vimasteprata.nu\/wp-content\/uploads\/2024\/11\/Spel-och-anhorig1-300x86.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>\u062e\u0637 \u0627\u0644\u062f\u0639\u0645 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0648\u0623\u0642\u0627\u0631\u0628\u0647\u0645<\/strong><br>\u0647\u0644 \u0623\u0646\u062a \u0642\u0644\u0642 \u0628\u0634\u0623\u0646 \u0645\u0642\u0627\u0645\u0631\u062a\u0643 \u0623\u0648 \u0645\u0642\u0627\u0645\u0631\u0629 \u0634\u062e\u0635 \u0622\u062e\u0631\u061f <br>\u0627\u062a\u0635\u0644 \u0623\u0648 \u062a\u062d\u062f\u062b \u0645\u0639\u0646\u0627. <br>\u0644\u0627 \u064a\u0643\u0644\u0641 \u0634\u064a\u0626\u064b\u0627 \u0648\u0644\u064a\u0633 \u0639\u0644\u064a\u0643 \u0623\u0646 \u062a\u062e\u0628\u0631\u0646\u0627 \u0645\u0646 \u0623\u0646\u062a.<br><br><br><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-25610177 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:60px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"\/ar\/\u0627\u0644\u0647\u0627\u062a\u0641: +4620-819100\/\" class=\"ub_icon_wrapper\"><?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 108.5\" style=\"enable-background:new 0 0 122.88 108.5\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M41.96,0h38.96c2.97,0,5.65,1.21,7.61,3.16c1.95,1.95,3.16,4.64,3.16,7.61v86.97c0,2.97-1.21,5.65-3.16,7.61 c-1.95,1.95-4.64,3.16-7.61,3.16H41.96c-2.97,0-5.65-1.21-7.61-3.16c-1.95-1.95-3.16-4.64-3.16-7.61V10.77 c0-2.97,1.21-5.65,3.16-7.61C36.3,1.21,39,0,41.96,0L41.96,0L41.96,0z M10.99,39.18c1.8-2-1.19-4.76-3.04-2.79l-0.03,0.03 C-2.58,47.79-2.63,60.58,7.72,72.08l0.01,0.01l0,0l0.03,0.03c1.91,1.97,4.82-0.86,3.03-2.8C1.76,59.25,1.99,49,10.82,39.33 C10.89,39.28,10.94,39.24,10.99,39.18L10.99,39.18L10.99,39.18z M111.89,39.18c-1.8-2,1.19-4.76,3.04-2.79l0.03,0.03 c10.51,11.37,10.56,24.16,0.21,35.65l-0.01,0.01l0,0l-0.03,0.03c-1.91,1.97-4.82-0.86-3.03-2.8c9.03-10.07,8.8-20.32-0.04-29.99 C111.99,39.28,111.94,39.24,111.89,39.18L111.89,39.18L111.89,39.18z M103.06,46.22c-1.66-2.12,1.49-4.62,3.17-2.61l0.03,0.04 c5.7,6.69,5.95,14.63,0.54,21.58c-1.65,2.16-4.91-0.36-3.26-2.51l0.01-0.02c3.34-4.3,4.35-9.29,1.05-14.04 C104.12,47.99,103.59,47.22,103.06,46.22L103.06,46.22L103.06,46.22z M19.82,46.22c1.66-2.12-1.49-4.62-3.17-2.61l-0.03,0.04 c-5.7,6.69-5.95,14.63-0.54,21.58c1.65,2.16,4.91-0.36,3.26-2.51l-0.01-0.02c-3.34-4.3-4.35-9.29-1.05-14.04 C18.76,47.99,19.29,47.22,19.82,46.22L19.82,46.22L19.82,46.22z M61.44,96.79c2.43,0,4.41,1.98,4.41,4.41 c0,2.43-1.98,4.41-4.41,4.41c-2.43,0-4.41-1.98-4.41-4.41C57.03,98.77,59,96.79,61.44,96.79L61.44,96.79L61.44,96.79z M34.29,93.41 H88.6V13.54H34.29V93.41L34.29,93.41z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-layout-constrained wp-block-column-is-layout-constrained\"><div style=\"--ub-icon-rotation:rotate(0deg);--ub-icon-size:70px;--ub-icon-justification:center;--ub-icon-border-top:  undefined;--ub-icon-border-right:  undefined;--ub-icon-border-bottom:  undefined;--ub-icon-border-left:  undefined\" class=\"wp-block-ub-icon\" id=\"ub-icon-\"><div class=\"ub_icon\"><a href=\"https:\/\/stodlinjen.se\/\" class=\"ub_icon_wrapper\" target=\"_blank\" rel=\"noopener\">\n<?xml version=\"1.0\" encoding=\"utf-8\"?><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 122.88 70.51\" style=\"enable-background:new 0 0 122.88 70.51\" xml:space=\"preserve\"><style type=\"text\/css\">.st0{fill-rule:evenodd;clip-rule:evenodd;}<\/style><g><path class=\"st0\" d=\"M2.54,65.44h12.59c-0.93-0.24-1.63-1.1-1.63-2.1V2.17C13.5,0.98,14.48,0,15.67,0h90.97 c1.19,0,2.17,0.98,2.17,2.17v61.16c0,1.01-0.69,1.86-1.63,2.1h13.16c1.4,0,2.54,1.14,2.54,2.54v0c0,1.4-1.14,2.54-2.54,2.54H2.54 c-1.4,0-2.54-1.14-2.54-2.54v0C0,66.58,1.14,65.44,2.54,65.44L2.54,65.44z M17.21,3.4h88.19v59.32H17.21V3.4L17.21,3.4z M57.87,66.39h7.14c0.67,0,1.22,0.55,1.22,1.22l0,0c0,0.67-0.55,1.22-1.22,1.22h-7.14c-0.67,0-1.22-0.55-1.22-1.22l0,0 C56.65,66.93,57.2,66.39,57.87,66.39L57.87,66.39z\"><\/path><\/g><\/svg><\/a><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-foreground-color has-tertiary-background-color has-text-color has-background has-link-color has-large-font-size wp-elements-1\" style=\"border-style:none;border-width:0px;border-radius:15px\">\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0627\u0644\u062a\u062d\u062f\u062b \u0627\u0644\u0622\u0646\u060c<br>\u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0627\u0644\u062a\u064a \u062a\u062d\u062a\u0627\u062c\u0647\u0627\u060c <br>\u0639\u0646\u062f\u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0625\u0644\u064a\u0647\u0627<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>SOS ALARMSveriges n\u00f6dnummer vid akut hj\u00e4lp. N\u00f6dnumret 112 ska anv\u00e4ndas vid akuta n\u00f6dsituationer d\u00e5 det \u00e4r fara f\u00f6r liv, egendom eller milj\u00f6. MIND Sj\u00e4lvmordslinjenSt\u00f6d f\u00f6r personer som har sj\u00e4lvmordstankar eller \u00e4r i kris. Ring eller chatta med MIND direkt.Finns tips &amp; st\u00f6d f\u00f6r psykisk oh\u00e4lsa. Hj\u00e4lplinjenHj\u00e4lplinjen \u00e4r en anonym och kostnadsfri st\u00f6dtj\u00e4nst f\u00f6r dig \u00f6ver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":197,"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":937,"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/pages\/74\/revisions\/937"}],"wp:attachment":[{"href":"https:\/\/vimasteprata.nu\/ar\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}